{"id":2771,"date":"2026-09-02T09:51:21","date_gmt":"2026-09-02T09:51:21","guid":{"rendered":"https:\/\/www.ccfbg.net\/?post_type=tribe_events&#038;p=2771"},"modified":"2026-09-02T09:51:21","modified_gmt":"2026-09-02T09:51:21","slug":"jeudi-cinema-lhistoire-de-souleymane","status":"publish","type":"tribe_events","link":"https:\/\/www.ccfbg.net\/index.php\/eventos\/jeudi-cinema-lhistoire-de-souleymane\/","title":{"rendered":"Jeudi Cin\u00e9ma: &#8220;L\u2019Histoire de Souleymane&#8221;"},"content":{"rendered":"<p>Jeudi Cin\u00e9ma \u2013 jeudi 17 septembre \u00e0 19h<\/p>\n<p>Cette semaine, Jeudi Cin\u00e9ma vous propose L\u2019Histoire de Souleymane, de Boris Lojkine, l\u2019un des films fran\u00e7ais les plus remarqu\u00e9s et r\u00e9compens\u00e9s de 2024.<\/p>\n<p>Souleymane, jeune Guin\u00e9en de Conakry sans titre de s\u00e9jour, sillonne Paris \u00e0 v\u00e9lo pour livrer des repas. Dans deux jours, il doit passer l\u2019entretien d\u00e9cisif de sa demande d\u2019asile. Entre les courses, la pr\u00e9carit\u00e9 et la pression du temps, il tente de se pr\u00e9parer \u00e0 ce rendez-vous qui peut changer sa vie.<\/p>\n<p>Pr\u00e9sent\u00e9 au Festival de Cannes 2024 dans la s\u00e9lection Un Certain Regard, le film y a remport\u00e9 deux r\u00e9compenses : le Prix du Jury et le Prix du meilleur acteur pour Abou Sangar\u00e9. Originaire de Guin\u00e9e-Conakry, Abou Sangar\u00e9 n\u2019\u00e9tait pas acteur professionnel : m\u00e9canicien de formation, il interpr\u00e8te ici son tout premier r\u00f4le au cin\u00e9ma. Sa performance exceptionnelle lui vaudra \u00e9galement le C\u00e9sar 2025 de la meilleure r\u00e9v\u00e9lation masculine.<\/p>\n<p>\u00c0 la fois haletant, humain et profond\u00e9ment ancr\u00e9 dans la r\u00e9alit\u00e9 contemporaine, L\u2019Histoire de Souleymane porte un regard sans clich\u00e9s sur l\u2019exil, le travail, la pr\u00e9carit\u00e9 et l\u2019espoir de construire une nouvelle vie.<\/p>\n<p>Bande-annonce officielle : <a href=\"https:\/\/www.youtube.com\/watch?v=CCMvdrBkb6w\">https:\/\/www.youtube.com\/watch?v=CCMvdrBkb6w<\/a><\/p>\n<p>Film pr\u00e9sent\u00e9 en fran\u00e7ais, sous-titr\u00e9 en portugais<br \/>\nDur\u00e9e : 1h32<br \/>\n\u00c2ge conseill\u00e9 : \u00e0 partir de 12 ans<\/p>\n<p>Entr\u00e9e libre<br \/>\nCCFBG \u2013 Pra\u00e7a Che Guevara, Bissau<\/p>\n<p>Jeudi Cinema \u2013 quinta-feira, 17 de setembro, \u00e0s 19h<\/p>\n<p>Esta semana, o Jeudi Cinema apresenta L\u2019Histoire de Souleymane, de Boris Lojkine, um dos filmes franceses mais premiados e elogiados de 2024.<\/p>\n<p>Souleymane, um jovem da Guin\u00e9-Conacri sem t\u00edtulo de resid\u00eancia, percorre Paris de bicicleta fazendo entregas de refei\u00e7\u00f5es. Dentro de dois dias, ter\u00e1 uma entrevista decisiva para o seu pedido de asilo. Entre as entregas, a precariedade e a press\u00e3o do tempo, tenta preparar-se para um encontro que poder\u00e1 mudar a sua vida.<\/p>\n<p>Apresentado no Festival de Cannes 2024, na sele\u00e7\u00e3o Un Certain Regard, o filme recebeu dois pr\u00e9mios: o Pr\u00e9mio do J\u00fari e o Pr\u00e9mio de Melhor Ator para Abou Sangar\u00e9. Origin\u00e1rio da Guin\u00e9-Conacri, Abou Sangar\u00e9 n\u00e3o era ator profissional: mec\u00e2nico de forma\u00e7\u00e3o, interpreta aqui o seu primeiro papel no cinema. A sua extraordin\u00e1ria interpreta\u00e7\u00e3o valeu-lhe tamb\u00e9m o C\u00e9sar 2025 de Melhor Revela\u00e7\u00e3o Masculina.<\/p>\n<p>Intenso, humano e profundamente ligado \u00e0 realidade contempor\u00e2nea, L\u2019Histoire de Souleymane apresenta, sem clich\u00e9s, um olhar sobre o ex\u00edlio, o trabalho, a precariedade e a esperan\u00e7a de construir uma nova vida.<\/p>\n<p>Trailer oficial: <a href=\"https:\/\/www.youtube.com\/watch?v=CCMvdrBkb6w\">https:\/\/www.youtube.com\/watch?v=CCMvdrBkb6w<\/a><\/p>\n<p>Filme apresentado em franc\u00eas, com legendas em portugu\u00eas<br \/>\nDura\u00e7\u00e3o: 1h32<br \/>\nIdade recomendada: a partir dos 12 anos<\/p>\n<p>Entrada livre<br \/>\nCCFBG \u2013 Pra\u00e7a Che Guevara, Bissau<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeudi Cin\u00e9ma \u2013 jeudi 17 septembre \u00e0 19h Cette semaine, Jeudi Cin\u00e9ma vous propose L\u2019Histoire de Souleymane, de Boris Lojkine, l\u2019un des films fran\u00e7ais les plus remarqu\u00e9s et r\u00e9compens\u00e9s de&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2772,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[12],"class_list":["post-2771","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-cinema","cat_cinema"],"_links":{"self":[{"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/tribe_events\/2771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/comments?post=2771"}],"version-history":[{"count":1,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/tribe_events\/2771\/revisions"}],"predecessor-version":[{"id":2773,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/tribe_events\/2771\/revisions\/2773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/media\/2772"}],"wp:attachment":[{"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/media?parent=2771"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/tags?post=2771"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.ccfbg.net\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=2771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}